{"id":243,"date":"2025-01-23T17:49:27","date_gmt":"2025-01-23T16:49:27","guid":{"rendered":"https:\/\/www.belle-fontaine.ch\/?page_id=243"},"modified":"2026-03-09T16:09:24","modified_gmt":"2026-03-09T15:09:24","slug":"declaration-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-243","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration de confidentialit\u00e9 - Clinique Bellefontaine<\/title>\n<meta name=\"description\" content=\"Cette d\u00e9claration de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour le mars 11, 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00e9conomique europ\u00e9en et de la Suisse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration de confidentialit\u00e9 - Clinique Bellefontaine\" \/>\n<meta property=\"og:description\" content=\"Cette d\u00e9claration de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour le mars 11, 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00e9conomique europ\u00e9en et de la Suisse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinique Bellefontaine\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T15:09:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/declaration-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/declaration-de-confidentialite\\\/\",\"name\":\"D\u00e9claration de confidentialit\u00e9 - Clinique Bellefontaine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/#website\"},\"datePublished\":\"2025-01-23T16:49:27+00:00\",\"dateModified\":\"2026-03-09T15:09:24+00:00\",\"description\":\"Cette d\u00e9claration de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour le mars 11, 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00e9conomique europ\u00e9en et de la Suisse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/declaration-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/declaration-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/declaration-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/\",\"name\":\"BelleFontaine\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belle-fontaine.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration de confidentialit\u00e9 - Clinique Bellefontaine","description":"Cette d\u00e9claration de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour le mars 11, 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00e9conomique europ\u00e9en et de la Suisse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration de confidentialit\u00e9 - Clinique Bellefontaine","og_description":"Cette d\u00e9claration de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour le mars 11, 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00e9conomique europ\u00e9en et de la Suisse.","og_url":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/","og_site_name":"Clinique Bellefontaine","article_modified_time":"2026-03-09T15:09:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/","url":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/","name":"D\u00e9claration de confidentialit\u00e9 - Clinique Bellefontaine","isPartOf":{"@id":"https:\/\/www.belle-fontaine.ch\/fr\/#website"},"datePublished":"2025-01-23T16:49:27+00:00","dateModified":"2026-03-09T15:09:24+00:00","description":"Cette d\u00e9claration de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour le mars 11, 2024 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00e9conomique europ\u00e9en et de la Suisse.","breadcrumb":{"@id":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.belle-fontaine.ch\/fr\/declaration-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belle-fontaine.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9claration de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.belle-fontaine.ch\/fr\/#website","url":"https:\/\/www.belle-fontaine.ch\/fr\/","name":"BelleFontaine","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belle-fontaine.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/pages\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/comments?post=243"}],"version-history":[{"count":0,"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/pages\/243\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.belle-fontaine.ch\/fr\/wp-json\/wp\/v2\/media?parent=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}